{"id":24956,"date":"2016-02-25T23:31:29","date_gmt":"2016-02-26T04:01:29","guid":{"rendered":"http:\/\/gradadigital.com\/home\/?p=24956"},"modified":"2016-02-26T04:33:13","modified_gmt":"2016-02-26T09:03:13","slug":"tachira-lo-dejo-escapar-sobre-el-final-ante-emelec","status":"publish","type":"post","link":"http:\/\/gradadigital.com\/home\/tachira-lo-dejo-escapar-sobre-el-final-ante-emelec\/","title":{"rendered":"T\u00e1chira lo dej\u00f3 escapar sobre el final ante Emelec"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24960\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2016\/02\/jorge_rojas_emelec_tachira_25022016-1.jpg\" alt=\"jorge_rojas_emelec_tachira_25022016\" width=\"682\" height=\"455\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2016\/02\/jorge_rojas_emelec_tachira_25022016-1.jpg 682w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2016\/02\/jorge_rojas_emelec_tachira_25022016-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>EFE &#8211;<\/strong> Emelec se sobrepuso con autoridad a la derrota por 4-2 ante los Pumas en del debut en la fase de grupos de la Copa Libertadores, al vencer hoy en Porto Viejo por 2-0 al Deportivo T\u00e1chira en la segunda jornada del grupo 7.<\/p>\n<p style=\"text-align: justify;\">La formaci\u00f3n ecuatoriana luch\u00f3 durante casi todo el partido para romper el cerrojo del equipo venezolano y sobre el final, en un intervalo de cuatro minutos, hizo suyo el partido.<\/p>\n<p style=\"text-align: justify;\">El argentino Emanuel Herrera convirti\u00f3 de penalti el primer gol en el minuto 80 y cuatro minutos despu\u00e9s sentenci\u00f3 su compatriota Denis Stracqualursi.<\/p>\n<p style=\"text-align: justify;\">El equipo venezolano qued\u00f3 con diez jugadores al minuto 86 al recibir la segunda amonestaci\u00f3n el defensa Carlos Lujano.<br \/>\nDeportivo T\u00e1chira tendi\u00f3 una telara\u00f1a defensiva con la que quit\u00f3 claridad ofensiva al local que tuvo el control del bal\u00f3n y de las acciones.<\/p>\n<p style=\"text-align: justify;\">Mientras el local se insinu\u00f3 constantemente sobre la porter\u00eda de Jos\u00e9 Contreras, el visitante esper\u00f3 pacientemente alg\u00fan error defensivo para procurar llegar al arco de Esteban Dreer.<\/p>\n<p style=\"text-align: justify;\">La \u00fanica posibilidad clara para anotar se la perdi\u00f3 el centrocampista argentino de Emelec Cristian Guanca al minuto 41, pues cabece\u00f3 a un costado del arco un centro preciso de Fernando Gim\u00e9nez.<\/p>\n<p style=\"text-align: justify;\">Marcelo Moreno, que reemplaz\u00f3 al \u2018Maestrico\u2019 Gonz\u00e1lez, se perdi\u00f3 una opci\u00f3n de gol, en un contraataque qued\u00f3 solo frente a Dreer pero su remate fue directo a la humanidad del portero, al minuto 73.<\/p>\n<p style=\"text-align: justify;\">El argentino Herrera tambi\u00e9n se perdi\u00f3 una posibilidad, pues enfrent\u00f3 solo al portero pero su d\u00e9bil remate se fue a un costado, al minuto 73.<\/p>\n<p style=\"text-align: justify;\">Con un penalti Emelec rompi\u00f3 el equilibrio a trav\u00e9s del argentino Herrera.<\/p>\n<p style=\"text-align: justify;\">Su compatriota Stracqualursi puso la guinda con un cabezazo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EFE &#8211; Emelec se sobrepuso con autoridad a la derrota por 4-2 ante los Pumas en del debut en la fase de grupos de la Copa Libertadores, al vencer hoy en Porto Viejo por 2-0 al Deportivo T\u00e1chira en la segunda jornada del grupo 7. La formaci\u00f3n ecuatoriana luch\u00f3 durante casi todo el partido para &#8230;<\/p>\n","protected":false},"author":4,"featured_media":24960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[752,37,11],"tags":[],"class_list":["post-24956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appgd","category-copa-libertadores","category-deportivo-tachira"],"_links":{"self":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/24956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/comments?post=24956"}],"version-history":[{"count":3,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/24956\/revisions"}],"predecessor-version":[{"id":24961,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/24956\/revisions\/24961"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media\/24960"}],"wp:attachment":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media?parent=24956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/categories?post=24956"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/tags?post=24956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}