{"id":19413,"date":"2015-03-24T12:00:55","date_gmt":"2015-03-24T16:30:55","guid":{"rendered":"http:\/\/gradadigital.com\/home\/?p=19413"},"modified":"2015-03-24T12:00:55","modified_gmt":"2015-03-24T16:30:55","slug":"maurice-cova-debemos-levantar-la-cara","status":"publish","type":"post","link":"http:\/\/gradadigital.com\/home\/maurice-cova-debemos-levantar-la-cara\/","title":{"rendered":"Maurice Cova: \u00abDebemos levantar la cara\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19414\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/03\/maurice_cova_trujillanos_metropolitanos_22032015.jpg\" alt=\"maurice_cova_trujillanos_metropolitanos_22032015\" width=\"682\" height=\"396\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/03\/maurice_cova_trujillanos_metropolitanos_22032015.jpg 682w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/03\/maurice_cova_trujillanos_metropolitanos_22032015-300x174.jpg 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16349\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd.jpg\" alt=\"banner_opcion_comentarios_gd\" width=\"621\" height=\"41\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd.jpg 621w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd-300x19.jpg 300w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd-620x41.jpg 620w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Prensa Oficial Trujillanos FC.-\u00a0<\/strong>Trujillanos FC no pudo sumar los tres puntos ante un duro rival que aprovech\u00f3 el \u00faltimo tramo del partido parar vencer a los guerreros. Para Maurice Cova Volante de los guerreros los noventa minutos se jugaron con mucho coraz\u00f3n \u201cfue un gran partido para ambos conjuntos, de esos partidos dif\u00edciles, luchados, nos planteamos muy bien en el campo de juego pero no mantuvimos como debimos el resultado\u201d<\/p>\n<p style=\"text-align: justify;\">En cuanto la derrota al final del partido coment\u00f3 que el Deportivo T\u00e1chira \u201cse nos vinieron encima y nos hacen dos goles que nos cuestan tres puntos\u201d. Cova dijo que la jugada del segundo gol no pudo aparecer una pierna guerrera para evitar el disparo \u201cfue una jugada en que ninguno pudo rechazar, en el segundo gol fue el \u00fanico rebote que les qued\u00f3 a ellos y lo supieron aprovechar para ganar el partido\u201d<\/p>\n<p style=\"text-align: justify;\">Cova destaca que los guerreros ahora deben \u201clevantar la cara porque hicimos un partido de t\u00fa a t\u00fa, Leandro en el arco estuvo bastante bien, todos los que estuvimos en cancha hicimos un trabajo espectacular al igual que los compa\u00f1eros de la reserva ante T\u00e1chira\u201d.<\/p>\n<p style=\"text-align: justify;\">En lo personal el marcado con la camiseta n\u00famero \u201c15\u201d jug\u00f3 un partido especial para s\u00ed mismo \u201cSal\u00ed al partido a disfrutar con responsabilidad y hacer mi trabajo de la mejor manera, contra T\u00e1chira siempre son bonitos partidos, pertenec\u00ed a esa instituci\u00f3n y eso siempre te da un plus para darlo todo en el compromiso l\u00e1stima que no nos alcanz\u00f3 para sumar\u201d.<\/p>\n<p style=\"text-align: justify;\">Ahora los guerreros deben pasar la p\u00e1gina y afrontar la semana de trabajo para enfrentar a su pr\u00f3ximo rival como lo es el Zulia FC en la ciudad de Valera \u201cvenimos haciendo un gran trabajo con buenos partidos, hoy no pudimos sumar a pesar del bueno juego que mostramos, tenemos y podemos sacar esto adelante, vamos a levantar la cara para esperar a nuestro pr\u00f3ximo rival en casa\u201d sentenci\u00f3 Cova.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.app.gradadigital\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15415\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014.jpg\" alt=\"banner_aplicacion_V2_GRADADIGITAL_17102014\" width=\"620\" height=\"100\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014.jpg 620w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014-300x48.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prensa Oficial Trujillanos FC.-\u00a0Trujillanos FC no pudo sumar los tres puntos ante un duro rival que aprovech\u00f3 el \u00faltimo tramo del partido parar vencer a los guerreros. Para Maurice Cova Volante de los guerreros los noventa minutos se jugaron con mucho coraz\u00f3n \u201cfue un gran partido para ambos conjuntos, de esos partidos dif\u00edciles, luchados, nos &#8230;<\/p>\n","protected":false},"author":4,"featured_media":19414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[752,5,31,19],"tags":[],"class_list":["post-19413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appgd","category-futbol-nacional","category-primera-division","category-trujillanos-fc"],"_links":{"self":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/comments?post=19413"}],"version-history":[{"count":1,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19413\/revisions"}],"predecessor-version":[{"id":19415,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19413\/revisions\/19415"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media\/19414"}],"wp:attachment":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media?parent=19413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/categories?post=19413"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/tags?post=19413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}