{"id":19240,"date":"2015-03-17T23:56:50","date_gmt":"2015-03-18T04:26:50","guid":{"rendered":"http:\/\/gradadigital.com\/home\/?p=19240"},"modified":"2015-03-18T12:54:04","modified_gmt":"2015-03-18T17:24:04","slug":"tachira-quiere-recobrar-el-triunfo-en-libertadores","status":"publish","type":"post","link":"http:\/\/gradadigital.com\/home\/tachira-quiere-recobrar-el-triunfo-en-libertadores\/","title":{"rendered":"T\u00e1chira quiere recobrar el triunfo en Libertadores"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/02\/estadio_pueblo_nuevo_tachira_racing_17022015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18555\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/02\/estadio_pueblo_nuevo_tachira_racing_17022015.jpg\" alt=\"estadio_pueblo_nuevo_tachira_racing_17022015\" width=\"682\" height=\"396\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/02\/estadio_pueblo_nuevo_tachira_racing_17022015.jpg 682w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2015\/02\/estadio_pueblo_nuevo_tachira_racing_17022015-300x174.jpg 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><a href=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16349\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd.jpg\" alt=\"banner_opcion_comentarios_gd\" width=\"621\" height=\"41\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd.jpg 621w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd-300x19.jpg 300w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/12\/banner_opcion_comentarios_gd-620x41.jpg 620w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Luiyi Joan Vivas \/ Prensa Deportivo T\u00e1chira &#8211;\u00a0<\/strong>Buscando imponer las condiciones en su feudo, el Deportivo T\u00e1chira F.C. salta por sexta vez en el a\u00f1o al ruedo internacional, cuando este mi\u00e9rcoles 18 de marzo se mida al Club Guaran\u00ed de Paraguay, en partido enmarcado en la Jornada 4 del Grupo 8 de la Copa Bridgestone Libertadores 2015, que se cumplir\u00e1 desde las 8:30 de la noche (hora venezolana).<\/p>\n<p style=\"text-align: justify;\">Luego de haber vencido de manera contundente a Mineros de Guayana por marcador de 5-2, en la fecha 10 del Torneo Clausura 2015 de la Liga Movistar, los dirigidos por Daniel Far\u00edas reciben en el Estadio Polideportivo de Pueblo Nuevo al tambi\u00e9n elenco aurinegro de la capital paraguaya, con la necesidad imperiosa de sumar de a tres.<\/p>\n<p style=\"text-align: justify;\">En el primer cotejo entre ambas escuadras, efectuado el pasado martes 10 de febrero en el Estadio Defensores del Chaco de Asunci\u00f3n, los locales vencieron 5-2 a los tachirenses, en un encuentro donde anotaron Ram\u00f3n Ocampo, Jorge Mendoza, Federico Santander desde el punto penalti, Juli\u00e1n Ben\u00edtez y Fernando Fern\u00e1ndez por Guaran\u00ed; mientras que C\u00e9sar \u201cMaestrico\u201d Gonz\u00e1lez y Javier L\u00f3pez concretaron por los de San Crist\u00f3bal.<\/p>\n<p style=\"text-align: justify;\">Los resultados anteriores del Carrusel Aurinegro indican ca\u00edda en casa frente a Racing Club de Argentina y empate a domicilio ante Sporting Cristal de Per\u00fa, realidad que lo ubica en la \u00faltima casilla de su zona con un punto, despu\u00e9s de tres salidas con tres goles marcados y once recibidos. Antes, los efectivos amarillos y negros hab\u00edan eliminado en la Primera Fase a Cerro Porte\u00f1o con global de 4-3.<\/p>\n<p style=\"text-align: justify;\">La preparaci\u00f3n para medirse por segunda ocasi\u00f3n al aborigen atigrado, se cumpli\u00f3 desde el domingo y hasta el martes 17 de marzo en la Cancha Alterna de Pueblo Nuevo, all\u00ed los efectivos del Deportivo T\u00e1chira F.C. laboraron sin dejar cabos sueltos de cara a un partido trascendental para mantener posibilidades de acceder a los Octavos de Final.<\/p>\n<p style=\"text-align: justify;\">El Club Guaran\u00ed llega ubicado en la tercera casilla del Grupo 8 de la Copa Bridgestone Libertadores, donde ha conseguido victoria, empate y derrota en tres salidas para sumar cuatro unidades, teniendo ocho dianas a favor y misma cantidad en contra.<\/p>\n<p style=\"text-align: justify;\">A las 8:30 de la noche est\u00e1 pautada la disputa entre aurinegros venezolanos y paraguayos en el Templo Sagrado, recinto donde el combinado tachirense ya venci\u00f3 a Guaran\u00ed, cuando se enfrentaron el 16 de abril de 2009 por la justa continental, triunfando por 2-1 gracias a las anotaciones de Yonathan Del Valle y Marlon Fern\u00e1ndez.<\/p>\n<p style=\"text-align: justify;\"><strong>Wilker \u00c1ngel y Agnel Flores son bajas<\/strong><\/p>\n<p style=\"text-align: justify;\">Para esta cuarta prueba del Grupo 8 de la Copa Bridgestone Libertadores 2015, Daniel Far\u00edas no contar\u00e1 con Wilker \u00c1ngel, suspendido por acumulaci\u00f3n de tres tarjetas amarillas; ni con Agnel Flores, quien vio la tarjeta roja en el \u00faltimo partido en Paraguay. Estos nombres se suman al de Pablo Olivera, quien se mantiene alejado por lesi\u00f3n en su pierna derecha.<\/p>\n<p style=\"text-align: justify;\">La convocatoria del Deportivo T\u00e1chira F.C. est\u00e1 compuesta por:\u00a0Alan Liebeskind, Jos\u00e9 Contreras, Javier L\u00f3pez, Yuber Mosquera, Gerzon Chac\u00f3n, Carlos Lujano, Carlos Salazar, Carlos Rivero, Carlos Cerme\u00f1o, Francisco flores, Marcelo Moreno, Jorge Rojas, C\u00e9sar Gonz\u00e1lez, Yohandry Orozco, Jos\u00e9 Al\u00ed Meza, Jos\u00e9 Miguel Reyes, Gelm\u00edn Rivas, \u00c1ngel Osorio.<\/p>\n<p style=\"text-align: justify;\"><strong>Ficha del partido:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Deportivo T\u00e1chira F.C. (Venezuela) Vs Club Guaran\u00ed (Paraguay)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Fecha:<\/strong> Mi\u00e9rcoles 18\/03\/2015.<\/p>\n<p style=\"text-align: justify;\"><strong>Hora:<\/strong> 8:30pm (Venezuela).<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c1rbitro principal:<\/strong> Jos\u00e9 Hernando Buitrago (Colombia).<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c1rbitros asistentes:<\/strong> Wilmar Navarro (Colombia), Rafael Rivas (Colombia), Jos\u00e9 Luis Hoyo (Venezuela).<\/p>\n<p style=\"text-align: justify;\"><strong>Estadio:<\/strong> Pueblo Nuevo, San Crist\u00f3bal, estado T\u00e1chira.<\/p>\n<p style=\"text-align: justify;\"><strong>Incidencias:<\/strong> Jornada 4, Grupo 8, Copa Bridgestone Libertadores 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luiyi Joan Vivas \/ Prensa Deportivo T\u00e1chira &#8211;\u00a0Buscando imponer las condiciones en su feudo, el Deportivo T\u00e1chira F.C. salta por sexta vez en el a\u00f1o al ruedo internacional, cuando este mi\u00e9rcoles 18 de marzo se mida al Club Guaran\u00ed de Paraguay, en partido enmarcado en la Jornada 4 del Grupo 8 de la Copa Bridgestone &#8230;<\/p>\n","protected":false},"author":4,"featured_media":18555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[752,37,11,36],"tags":[],"class_list":["post-19240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appgd","category-copa-libertadores","category-deportivo-tachira","category-internacional"],"_links":{"self":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/comments?post=19240"}],"version-history":[{"count":1,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19240\/revisions"}],"predecessor-version":[{"id":19241,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/19240\/revisions\/19241"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media\/18555"}],"wp:attachment":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media?parent=19240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/categories?post=19240"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/tags?post=19240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}