{"id":15566,"date":"2014-10-26T22:51:58","date_gmt":"2014-10-27T03:21:58","guid":{"rendered":"http:\/\/gradadigital.com\/home\/?p=15566"},"modified":"2014-10-26T23:43:29","modified_gmt":"2014-10-27T04:13:29","slug":"la-paridad-se-presento-en-el-brigido-iriarte","status":"publish","type":"post","link":"http:\/\/gradadigital.com\/home\/la-paridad-se-presento-en-el-brigido-iriarte\/","title":{"rendered":"La paridad se present\u00f3 en el Br\u00edgido Iriarte"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/edgar_perez_greco_atlvenezuela_lara_26102014.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15567\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/edgar_perez_greco_atlvenezuela_lara_26102014.jpg\" alt=\"edgar_perez_greco_atlvenezuela_lara_26102014\" width=\"682\" height=\"396\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/edgar_perez_greco_atlvenezuela_lara_26102014.jpg 682w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/edgar_perez_greco_atlvenezuela_lara_26102014-300x174.jpg 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Jes\u00fas A. S\u00e1ez S. Caracas<\/strong> .- Atl\u00e9tico Venezuela y Deportivo Lara se repartieron los puntos, tras igualar en la und\u00e9cima fecha del Torneo Apertura 2014.<\/p>\n<p style=\"text-align: justify;\">Atl\u00e9tico Venezuela sigue viviendo su mejor momento en el presente campeonato, los dirigidos por Jos\u00e9 Hern\u00e1ndez vienen trabajando con mucho esfuerzo y por ende deb\u00edan seguir cosechando la racha ganadora en su propio campo. El conjunto local sab\u00eda que iban a enfrentar a un rival como el Deportivo Lara, que a pesar de que no est\u00e1 peleando arriba los primeros puestos, es un equipo que hace da\u00f1o y les urg\u00eda lograr una victoria de visitante, pero los objetivos de ambos equipos se quedaron cortos, y tuvieron que compartir los puntos en la tabla.<\/p>\n<p style=\"text-align: justify;\">El partido tuvo mucha intensidad desde el comienzo. Los dos conjuntos estaban en un tome y dame sin hacerse mucho da\u00f1o, la idea principal era conocerse y saber cuales ser\u00edan las estrategias para invadir el arco del rival. El combinado azul jugaba en reiteradas ocasiones por la banda derecha tratando de quebrantar la defensa rojinegra e intentando centrar sobre el \u00e1rea de diversas maneras, pero el Deportivo Lara cerraba a tiempo despejando el peligro inmediatamente.<\/p>\n<p style=\"text-align: justify;\">Cuando el reloj marcaba el minuto 19 Marlon Fern\u00e1ndez logr\u00f3 escaparse por la banda derecha con mucha facilidad y al quedar libre de marca, envi\u00f3 un centro que no pudo despejar bien la defensa del Atl\u00e9tico Venezuela, apareciendo de la nada Edgar P\u00e9rez Greco, quien cabece\u00f3 y concret\u00f3 el primer gol de la tarde, vacunando a los locales quienes no hab\u00edan recibido ning\u00fan tanto en casa durante el Apertura, aunque la alegr\u00eda s\u00f3lo dur\u00f3 unos minutos.<\/p>\n<p style=\"text-align: justify;\">Y es que el equipo capitalino segu\u00eda intentando a trav\u00e9s de su capit\u00e1n H\u00e9ctor P\u00e9rez que despu\u00e9s de varios intentos,\u00a0 supo enviar un centro a ras de piso adelant\u00e1ndose encontrando al argentino Leonardo Carboni que con solo tocarla de primera, igualaba las acciones en el Br\u00edgido Iriarte de la ciudad de Caracas.<\/p>\n<p style=\"text-align: justify;\">Para la segunda parte los papeles cambiaban y como ya se conoc\u00edan, la agresividad en el campo\u00a0 aparec\u00eda desde los primeros minutos, y sin mucho que esperar el Atl\u00e9tico Venezuela remontaba el cotejo, luego de una jugada de tiro de esquina que aprovech\u00f3 Daniel Mustaf\u00e1 para cabecear y esconder en el fondo de las redes la esf\u00e9rica para el 2-1 (46&#8242;) de la tarde.<\/p>\n<p style=\"text-align: justify;\">Tras ir abajo en el marcador el Deportivo Lara nunca baj\u00f3 los brazos y mucho menos se dej\u00f3 intimidar de los locales, por lo que probar\u00edan de varias formas pero sin efectividad las diversas jugadas que armaban, hasta que en el minuto 53 Armando Maita logr\u00f3 abatir el arco de Daniel Vald\u00e9s, ex portero del rojinegro, convirtiendo el segundo gol de los crespusculares (2-2).<\/p>\n<p style=\"text-align: justify;\">Mas tarde ambas oncenas protagonizaban oportunidades claras para seguir ampliando el marcador aunque la suerte no los acompa\u00f1aba. Una de ellas fue para el Atl\u00e9tico, que luego de un contragolpe y varios rebotes en el \u00e1rea, no pudo definir con claridad al final H\u00e9ctor P\u00e9rez, frustrando a la fanaticada que se dio cita para apoyar al equipo. De las misma forma sucedi\u00f3 con el Lara\u00a0 con Armando Maita quien no pudo definir con claridad en un mano a mano, Valdes ataj\u00f3 el disparo enviado por el delantero rojinegro.<\/p>\n<p style=\"text-align: justify;\">El resultado se manten\u00eda y el principal anunciaba la culminaci\u00f3n del encuentro, sumando otro empate\u00a0 el Deportivo Lara quienes les ha costado ganar en el presente campeonato a pesar de los esfuerzos en cada partido, pues hasta la fecha s\u00f3lo ha conseguido dos victorias, siete de empates y dos derrotas\u00a0 ubic\u00e1ndose en la casilla 11 de la tabla de posiciones. Mientras que el Atl\u00e9tico Venezuela con el punto rescatado, ocupa el puesto siete en el presente Torneo Apertura.<\/p>\n<p style=\"text-align: justify;\">En la fecha 12 los larenses reciben la visita de Llaneros de Guanare en el Metropolitano de Cabudare, y el conjunto capitalino se queda en en la ciudad pero en calidad de visitante enfrentar\u00e1 al l\u00edder, el Deportivo La Guaira en el Ol\u00edmpico de la UCV.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.app.gradadigital\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15415\" src=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014.jpg\" alt=\"banner_aplicacion_V2_GRADADIGITAL_17102014\" width=\"620\" height=\"100\" srcset=\"http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014.jpg 620w, http:\/\/gradadigital.com\/home\/wp-content\/uploads\/2014\/10\/banner_aplicacion_V2_GRADADIGITAL_17102014-300x48.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<div style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"http:\/\/gradadigital.com\/datafactory\/html\/venezuela\/ficha203698.html\" width=\"702\" height=\"1030\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas A. S\u00e1ez S. Caracas .- Atl\u00e9tico Venezuela y Deportivo Lara se repartieron los puntos, tras igualar en la und\u00e9cima fecha del Torneo Apertura 2014. Atl\u00e9tico Venezuela sigue viviendo su mejor momento en el presente campeonato, los dirigidos por Jos\u00e9 Hern\u00e1ndez vienen trabajando con mucho esfuerzo y por ende deb\u00edan seguir cosechando la racha ganadora &#8230;<\/p>\n","protected":false},"author":4,"featured_media":15567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[752,7,8,5,31],"tags":[],"class_list":["post-15566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appgd","category-atletico-venezuela","category-cd-lara","category-futbol-nacional","category-primera-division"],"_links":{"self":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/15566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/comments?post=15566"}],"version-history":[{"count":3,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/15566\/revisions"}],"predecessor-version":[{"id":15584,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/posts\/15566\/revisions\/15584"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media\/15567"}],"wp:attachment":[{"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/media?parent=15566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/categories?post=15566"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gradadigital.com\/home\/wp-json\/wp\/v2\/tags?post=15566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}